{"id":143,"date":"2023-12-04T19:16:51","date_gmt":"2023-12-04T18:16:51","guid":{"rendered":"https:\/\/marcrebuffo.com\/?page_id=143"},"modified":"2024-01-30T07:20:26","modified_gmt":"2024-01-30T06:20:26","slug":"contact-2","status":"publish","type":"page","link":"https:\/\/marcrebuffo.com\/index.php\/contact-2\/","title":{"rendered":"Contact"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left has-larger-font-size\">      Marc :  06 20 65 64 30<\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left has-larger-font-size\">rebuffo.marc@gmail.com<\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-right has-larger-font-size\">Karen : 06 16 62 80 88<\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-right has-larger-font-size\">               karen.apiculture@gmail.com <\/h2>\n\n\n<style id=\"wpforms-css-vars-149-block-a9782232-fb79-4192-b909-14d51c97667e\">\n\t\t\t\t#wpforms-149.wpforms-block-a9782232-fb79-4192-b909-14d51c97667e {\n\t\t\t\t--wpforms-label-size-font-size: 18px;\n--wpforms-label-size-line-height: 21px;\n--wpforms-label-size-sublabel-font-size: 16px;\n--wpforms-label-size-sublabel-line-height: 19px;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-a9782232-fb79-4192-b909-14d51c97667e wpforms-render-modern\" id=\"wpforms-149\"><form id=\"wpforms-form-149\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"149\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/143\" data-token=\"fe381a40572d587d538ec51983b51dd7\" data-token-time=\"1784150993\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-149-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><fieldset><legend class=\"wpforms-field-label\">Nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-149-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" aria-errormessage=\"wpforms-149-field_0-error\" required><label for=\"wpforms-149-field_0\" class=\"wpforms-field-sublabel after\">Pr\u00e9nom<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-149-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" aria-errormessage=\"wpforms-149-field_0-last-error\" required><label for=\"wpforms-149-field_0-last\" class=\"wpforms-field-sublabel after\">Nom<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-149-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-149-field_1\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-149-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-149-field_1-error\" required><\/div><div id=\"wpforms-149-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-149-field_2\">Commentaire ou message<\/label><textarea id=\"wpforms-149-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-149-field_2-error\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"149\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/marcrebuffo.com\/index.php\/wp-json\/wp\/v2\/pages\/143\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-149\" class=\"wpforms-submit\" data-alt-text=\"Envoi...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/marcrebuffo.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/marcrebuffo.com\/wp-content\/uploads\/2024\/01\/MARC-REBUFFO-bon-de-commande.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 MARC REBUFFO bon de commande.\"><\/object><a id=\"wp-block-file--media-dd82d1cd-dee5-4951-9a0c-c89d6e27f56e\" href=\"https:\/\/marcrebuffo.com\/wp-content\/uploads\/2024\/01\/MARC-REBUFFO-bon-de-commande.pdf\">MARC REBUFFO bon de commande<\/a><a href=\"https:\/\/marcrebuffo.com\/wp-content\/uploads\/2024\/01\/MARC-REBUFFO-bon-de-commande.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-dd82d1cd-dee5-4951-9a0c-c89d6e27f56e\">Download<\/a><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Marc : 06 20 65 64 30 rebuffo.marc@gmail.com Karen : 06 16 62 80 88 karen.apiculture@gmail.com<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-full-width.php","meta":{"footnotes":""},"class_list":["post-143","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/marcrebuffo.com\/index.php\/wp-json\/wp\/v2\/pages\/143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcrebuffo.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/marcrebuffo.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/marcrebuffo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marcrebuffo.com\/index.php\/wp-json\/wp\/v2\/comments?post=143"}],"version-history":[{"count":10,"href":"https:\/\/marcrebuffo.com\/index.php\/wp-json\/wp\/v2\/pages\/143\/revisions"}],"predecessor-version":[{"id":251,"href":"https:\/\/marcrebuffo.com\/index.php\/wp-json\/wp\/v2\/pages\/143\/revisions\/251"}],"wp:attachment":[{"href":"https:\/\/marcrebuffo.com\/index.php\/wp-json\/wp\/v2\/media?parent=143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}